{"id":20590,"date":"2015-01-15T16:19:08","date_gmt":"2015-01-15T15:19:08","guid":{"rendered":"http:\/\/huxlipux.de\/blog\/?p=20590"},"modified":"2015-01-15T17:19:15","modified_gmt":"2015-01-15T16:19:15","slug":"indien-im-hafen-von-mundra","status":"publish","type":"post","link":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/","title":{"rendered":"Indien &#8211; im Hafen von Mundra"},"content":{"rendered":"<pre>Wir liegen im Hafen und alles geht seinen Gang. \r\nHier werden richtig viele Container mitgenommen \r\nund viele der leeren, die wir an Bord hatten, \r\nausgeladen. Das Gleiche passiert dann nochmal \r\nin dem zweiten indischen Hafen, wo wir an Land \r\ngehen wollen. \r\nHeute will ich versuchen, aufzuschreiben, worin \r\ndie B\u00fcrot\u00e4tigkeit des Kapit\u00e4ns besteht, bevor \r\nwir einen Hafen anlaufen. \r\n\r\nWir haben uns vor ein paar \r\nTagen dar\u00fcber unterhalten, dass die meisten Leute \r\nwahrscheinlich denken, ein Kapit\u00e4n steuert das Schiff.\r\nPeti sagte mir, dass dies auch in alten Zeiten nicht \r\nso war. Aber heute hat sich das Berufsbild durch die \r\nmoderne Technik v\u00f6llig ver\u00e4ndert. Fr\u00fcher gab es Funker, \r\ndie die Korrespondenz an Bord regelten. Heute macht \r\ndas alles der Kapit\u00e4n. Er hat oben auf der Br\u00fccke den \r\nHauptcomputer. \r\n<a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20588\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg\" alt=\"IMG_4985\" width=\"285\" height=\"300\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg 285w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-350x367.jpg 350w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851.jpg 461w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a> Dort kommen alle Mails an und von da \r\nwerden sie auch weggeschickt. Peti empf\u00e4ngt Post von \r\nder Reederei, vom Charterer, von den Hafenbeh\u00f6rden und \r\nvon anderen Stellen. Er muss sie lesen und an die \r\nAdressaten verteilen. Jeder Hafen m\u00f6chte haufenweise \r\nDokumente haben. F\u00fcr diesen Hafen in Mundra trafen 15 \r\nMails ein. In jeder steht eine neue Forderung. Alles \r\nverstehe ich nicht, besonders die technischen Dinge \r\nsind mir meist ein R\u00e4tsel. Aber zum Beispiel brauchen \r\nalle H\u00e4fen mehrere Crewlisten. K\u00f6nnte einfach sein. \r\nMan k\u00f6nnte doch \u00fcberall die gleiche Liste ausdrucken. \r\nAber nein, jeder Hafen hat sein eigenes Formular und \r\nakzeptiert kein anderes. Auch die Reihenfolge ist \r\nunterschiedlich. Bei manchen steht der Vorname an \r\nerster Stelle, bei anderen der Familienname. Die P\u00e4sse \r\nm\u00fcssen kopiert werden. In Karatschi zum Beispiel \r\nbrauchten wir von jedem Pass zwei Kopien und dazu die \r\nSeemannspatente, die in  gro\u00dfen Mappen, \u00e4hnlich wie \r\nZeugnismappen jeder Seemann beim Aufsteigen auf ein \r\nSchiff beim Kapit\u00e4n abgibt. Da konnte ich mich beim \r\nKopieren ein wenig n\u00fctzlich machen. \r\nAndere Unterlagen m\u00fcssen \u00fcber das Schiff Auskunft geben. \r\nWie lang, wie breit, wie tief liegt es, wie ist es \r\nbeladen. Wie viel Brennstoff ist an Bord. Gibt es \r\nFrischwasser oder Trinkwasser. Gesundheits- und \r\nHygienebescheide m\u00fcssen auf dem neusten Stand sein. In \r\neinem Hafen musste sogar die K\u00f6rpertemperatur der \r\nBesatzung angegeben werden. Listen f\u00fcr den Zoll m\u00fcssen \r\nangefertigt werden. Darauf steht, welche technischen \r\nGer\u00e4te jeder mit sich f\u00fchrt und wie viel Geld. Bestimmte \r\nKontroll-,Besichtigungs-, und Wartungstermine werden \r\nvorbereitet. Zum Beispiel wird hier im Hafen ein \r\nriesengro\u00dfer Tank gereinigt. 33 Leute (Inder, nicht \r\ndie Besatzung) arbeiten an dieser Aufgabe. Das ist n\u00f6tig, \r\nweil in den USA, wohin das Schiff wieder f\u00e4hrt,\r\nsch\u00e4rfere Bestimmungen betreffs des Brennstoffs vorgegeben \r\nsind. Peti muss einige Unterlagen an die Reederei auch \r\nper Post verschicken. Und wenn der Computer kaputt ist, \r\nkriegt er ellenlange Anweisungen, wie er ihn reparieren \r\nsoll, wof\u00fcr er keine Zeit hat und was auch nicht zu \r\nseinem Aufgabenbereich geh\u00f6rt, weil es Wartungsvertr\u00e4ge \r\nmit einer Firma dazu gibt. Dann muss er sich mit den \r\nLeuten auseinandersetzen, bis sie dann von einem Hafen \r\nendlich jemanden schicken, der sich der Sache annimmt.\r\nSicher habe ich einiges nicht erw\u00e4hnt, bevor er an \r\nseinem Computer wieder irgendein Blatt ausf\u00fcllen muss.\r\n<a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/FullSizeRender1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20592\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/FullSizeRender1-300x225.jpg\" alt=\"FullSizeRender\" width=\"300\" height=\"225\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/FullSizeRender1-300x225.jpg 300w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/FullSizeRender1-350x262.jpg 350w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/FullSizeRender1.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>             So sieht es aus, wenn alles leer \r\n             ist und die Container fort sind\r\n\r\n\r\n<\/pre>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">Wir liegen im Hafen und alles geht seinen Gang. Hier werden richtig viele Container mitgenommen und viele der leeren, die wir an Bord hatten, ausgeladen. Das Gleiche passiert dann nochmal&hellip; <span class=\"more-link\">more<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-20590","post","type-post","status-publish","format-standard","hentry","category-reisen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Indien - im Hafen von Mundra - Huxlipux.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Indien - im Hafen von Mundra - Huxlipux.de\" \/>\n<meta property=\"og:description\" content=\"Wir liegen im Hafen und alles geht seinen Gang. Hier werden richtig viele Container mitgenommen und viele der leeren, die wir an Bord hatten, ausgeladen. Das Gleiche passiert dann nochmal&hellip; more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/\" \/>\n<meta property=\"og:site_name\" content=\"Huxlipux.de\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-15T15:19:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-15T16:19:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"461\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/\"},\"author\":{\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"headline\":\"Indien &#8211; im Hafen von Mundra\",\"datePublished\":\"2015-01-15T15:19:08+00:00\",\"dateModified\":\"2015-01-15T16:19:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/\"},\"wordCount\":6,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg\",\"articleSection\":[\"Reisen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/\",\"url\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/\",\"name\":\"Indien - im Hafen von Mundra - Huxlipux.de\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg\",\"datePublished\":\"2015-01-15T15:19:08+00:00\",\"dateModified\":\"2015-01-15T16:19:15+00:00\",\"author\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"breadcrumb\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#primaryimage\",\"url\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg\",\"contentUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/huxlipux.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Indien &#8211; im Hafen von Mundra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\",\"url\":\"https:\/\/huxlipux.de\/blog\/\",\"name\":\"Huxlipux.de\",\"description\":\"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/huxlipux.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\",\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"sameAs\":[\"http:\/\/www.huxlipux.de\"],\"url\":\"https:\/\/huxlipux.de\/blog\/author\/uweboe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Indien - im Hafen von Mundra - Huxlipux.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/","og_locale":"de_DE","og_type":"article","og_title":"Indien - im Hafen von Mundra - Huxlipux.de","og_description":"Wir liegen im Hafen und alles geht seinen Gang. Hier werden richtig viele Container mitgenommen und viele der leeren, die wir an Bord hatten, ausgeladen. Das Gleiche passiert dann nochmal&hellip; more","og_url":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/","og_site_name":"Huxlipux.de","article_published_time":"2015-01-15T15:19:08+00:00","article_modified_time":"2015-01-15T16:19:15+00:00","og_image":[{"width":461,"height":484,"url":"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851.jpg","type":"image\/jpeg"}],"author":"Ursula B\u00f6hnke-Kuckhoff","twitter_misc":{"Verfasst von":"Ursula B\u00f6hnke-Kuckhoff","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#article","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/"},"author":{"name":"Ursula B\u00f6hnke-Kuckhoff","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"headline":"Indien &#8211; im Hafen von Mundra","datePublished":"2015-01-15T15:19:08+00:00","dateModified":"2015-01-15T16:19:15+00:00","mainEntityOfPage":{"@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/"},"wordCount":6,"commentCount":0,"image":{"@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#primaryimage"},"thumbnailUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg","articleSection":["Reisen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/","url":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/","name":"Indien - im Hafen von Mundra - Huxlipux.de","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#primaryimage"},"image":{"@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#primaryimage"},"thumbnailUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg","datePublished":"2015-01-15T15:19:08+00:00","dateModified":"2015-01-15T16:19:15+00:00","author":{"@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"breadcrumb":{"@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#primaryimage","url":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg","contentUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2015\/01\/IMG_49851-285x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/huxlipux.de\/blog\/2015\/01\/indien-im-hafen-von-mundra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huxlipux.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Indien &#8211; im Hafen von Mundra"}]},{"@type":"WebSite","@id":"https:\/\/huxlipux.de\/blog\/#website","url":"https:\/\/huxlipux.de\/blog\/","name":"Huxlipux.de","description":"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huxlipux.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f","name":"Ursula B\u00f6hnke-Kuckhoff","sameAs":["http:\/\/www.huxlipux.de"],"url":"https:\/\/huxlipux.de\/blog\/author\/uweboe\/"}]}},"_links":{"self":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/20590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/comments?post=20590"}],"version-history":[{"count":3,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/20590\/revisions"}],"predecessor-version":[{"id":20595,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/20590\/revisions\/20595"}],"wp:attachment":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/media?parent=20590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/categories?post=20590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/tags?post=20590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}