{"id":1745,"date":"2011-11-01T06:04:32","date_gmt":"2011-11-01T05:04:32","guid":{"rendered":"http:\/\/huxlipux.de\/blog\/?p=1745"},"modified":"2011-12-17T09:19:08","modified_gmt":"2011-12-17T08:19:08","slug":"herbst","status":"publish","type":"post","link":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/","title":{"rendered":"F\u00fcr Oma und Opa und Dich!"},"content":{"rendered":"<p><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/11\/Schlechtelaunemaus.mp3\">Schlechtelaunemaus<\/a><\/p>\n<p>Kennst du das? Drau\u00dfen regnet es. Der Himmel ist grau.<br \/>\nDu bist nicht sehr fr\u00f6hlich. Du murrst und hast auch noch Langeweile.<br \/>\nDann h\u00f6r dir das Schlechtelaunemaus-Lied an.<br \/>\nGleich wird es dir besser gehen.<\/p>\n<p><span style=\"color: #ff0000;\">\u00a0 &lt;^^&gt;\u00a0\u00a0<\/span><span style=\"color: #008000;\"> &lt;^^&gt;\u00a0<\/span> <span style=\"color: #0000ff;\">&lt;^^&gt;<\/span><\/p>\n<h4>Herbst<\/h4>\n<p>Wohl ist es Herbst, doch warte nur,<br \/>\ndoch warte nur ein Weilchen!<br \/>\nDer Fr\u00fchling kommt, der Himmel lacht,<br \/>\nes steht die Welt in Veilchen.<\/p>\n<p><em>von Theodor Storm<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Wer noch nicht so viel behalten kann, k\u00f6nnte dieses Verslein bis zum Oma-Opa-Tag lernen und ihnen zur Freude aufsagen!<\/p>\n<p>Und hier noch ein paar andere Gedichte von Christian Morgenstern, die Oma oder Opa bestimmt kennen und vielleicht auch m\u00f6gen. Probiere es aus!<\/p>\n<h4>Von dem gro\u00dfen Elefanten<\/h4>\n<p>Kennst du den gro\u00dfen Elefanten,<br \/>\ndu wei\u00dft, den Onkel von den Tanten,<br \/>\nden ganz ganz gro\u00dfen, wei\u00dft du, der &#8211;<br \/>\nder immer so macht, hin und her?<\/p>\n<p>Der l\u00e4sst dich n\u00e4mlich vielmals gr\u00fc\u00dfen,<br \/>\ner hat mit seinen eignen F\u00fc\u00dfen<br \/>\nhineingeschrieben in den Sand:<br \/>\nGr\u00fc\u00df mir Sophiechen Windelband!<\/p>\n<p>Du darfst mir ja nicht dr\u00fcber lachen.<br \/>\nWenn Elefanten etwas machen,<br \/>\nso ist dies selten, meiner Seel!<br \/>\nWeit seltener als bei dem Kamel.<\/p>\n<p>&nbsp;<\/p>\n<h4>Der Lattenzaun<\/h4>\n<p>Es war einmal ein Lattenzaun,<br \/>\nmit Zwischenraum, hindurch zu schaun.<\/p>\n<p>Ein Architekt, der dieses sah,<br \/>\nstand eines Abends pl\u00f6tzlich da.<\/p>\n<p>und nahm den Zwischenraum heraus<br \/>\nund baute draus ein gro\u00dfes Haus.<\/p>\n<p>Der Zaun indessen stand ganz dumm<br \/>\nmit Latten ohne was herum.<\/p>\n<p>Ein Anblick gr\u00e4sslich und gemein.<br \/>\nDrum zog ihn der Senat auch ein.<\/p>\n<p>Der Architekt jedoch entfloh<br \/>\nnach Afri- od- Ameriko.<\/p>\n<p>&nbsp;<\/p>\n<h4>Der Sperling und das K\u00e4nguruh<\/h4>\n<p>In seinem Zaun das K\u00e4nguruh &#8211;<br \/>\nes hockt und guckt dem Sperling zu.<\/p>\n<p>Der Sperling sitzt auf dem Geb\u00e4ude &#8211;<br \/>\ndoch ohne sonderliche Freude.<\/p>\n<p>Vielmehr, er f\u00fchlt, den Kopf geduckt,<br \/>\nwie ihn das K\u00e4nguruh beguckt.<\/p>\n<p>Der Sperling str\u00e4ubt den Federflaus &#8211;<br \/>\ndie\u00a0 Sache ist auch gar zu kraus.<\/p>\n<p>Ihm ist, als ob er kaum noch s\u00e4\u00dfe&#8230;<br \/>\nWenn nun das K\u00e4nguruh ihn fr\u00e4\u00dfe?<\/p>\n<p>Doch dieses dreht nach einer Stunde<br \/>\nden Kopf aus irgend einem Grunde<\/p>\n<p>vielleicht auch ohne tiefern Sinn,<br \/>\nnach einer andern Richtung hin.<\/p>\n<p>&nbsp;<\/p>\n<h2>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <span style=\"color: #008000;\">Am 12. November<\/span><\/h2>\n<h2><\/h2>\n<h1><span style=\"color: #ff0000;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 O<\/span><span style=\"color: #008000;\">m<span style=\"color: #ffcc00;\">a-<\/span><\/span><span style=\"color: #0000ff;\">O<\/span><span style=\"color: #ff99cc;\">p<\/span><span style=\"color: #993366;\">a<\/span><span style=\"color: #ff00ff;\">-T<span style=\"color: #cc99ff;\">a<\/span><\/span><span style=\"color: #99cc00;\">g!<\/span><\/h1>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">Schlechtelaunemaus Kennst du das? Drau\u00dfen regnet es. Der Himmel ist grau. Du bist nicht sehr fr\u00f6hlich. Du murrst und hast auch noch Langeweile. Dann h\u00f6r dir das Schlechtelaunemaus-Lied an. Gleich&hellip; <span class=\"more-link\">more<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1745","post","type-post","status-publish","format-standard","hentry","category-kindergalerie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00fcr Oma und Opa und Dich! - Huxlipux.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fcr Oma und Opa und Dich! - Huxlipux.de\" \/>\n<meta property=\"og:description\" content=\"Schlechtelaunemaus Kennst du das? Drau\u00dfen regnet es. Der Himmel ist grau. Du bist nicht sehr fr\u00f6hlich. Du murrst und hast auch noch Langeweile. Dann h\u00f6r dir das Schlechtelaunemaus-Lied an. Gleich&hellip; more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/\" \/>\n<meta property=\"og:site_name\" content=\"Huxlipux.de\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-01T05:04:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-12-17T08:19:08+00:00\" \/>\n<meta name=\"author\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/\"},\"author\":{\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"headline\":\"F\u00fcr Oma und Opa und Dich!\",\"datePublished\":\"2011-11-01T05:04:32+00:00\",\"dateModified\":\"2011-12-17T08:19:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/\"},\"wordCount\":390,\"commentCount\":0,\"articleSection\":[\"Kindergalerie\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/\",\"url\":\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/\",\"name\":\"F\u00fcr Oma und Opa und Dich! - Huxlipux.de\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\"},\"datePublished\":\"2011-11-01T05:04:32+00:00\",\"dateModified\":\"2011-12-17T08:19:08+00:00\",\"author\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"breadcrumb\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/huxlipux.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00fcr Oma und Opa und Dich!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\",\"url\":\"https:\/\/huxlipux.de\/blog\/\",\"name\":\"Huxlipux.de\",\"description\":\"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/huxlipux.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\",\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"sameAs\":[\"http:\/\/www.huxlipux.de\"],\"url\":\"https:\/\/huxlipux.de\/blog\/author\/uweboe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00fcr Oma und Opa und Dich! - Huxlipux.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/","og_locale":"de_DE","og_type":"article","og_title":"F\u00fcr Oma und Opa und Dich! - Huxlipux.de","og_description":"Schlechtelaunemaus Kennst du das? Drau\u00dfen regnet es. Der Himmel ist grau. Du bist nicht sehr fr\u00f6hlich. Du murrst und hast auch noch Langeweile. Dann h\u00f6r dir das Schlechtelaunemaus-Lied an. Gleich&hellip; more","og_url":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/","og_site_name":"Huxlipux.de","article_published_time":"2011-11-01T05:04:32+00:00","article_modified_time":"2011-12-17T08:19:08+00:00","author":"Ursula B\u00f6hnke-Kuckhoff","twitter_misc":{"Verfasst von":"Ursula B\u00f6hnke-Kuckhoff","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/#article","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/"},"author":{"name":"Ursula B\u00f6hnke-Kuckhoff","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"headline":"F\u00fcr Oma und Opa und Dich!","datePublished":"2011-11-01T05:04:32+00:00","dateModified":"2011-12-17T08:19:08+00:00","mainEntityOfPage":{"@id":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/"},"wordCount":390,"commentCount":0,"articleSection":["Kindergalerie"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/","url":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/","name":"F\u00fcr Oma und Opa und Dich! - Huxlipux.de","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/#website"},"datePublished":"2011-11-01T05:04:32+00:00","dateModified":"2011-12-17T08:19:08+00:00","author":{"@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"breadcrumb":{"@id":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/huxlipux.de\/blog\/2011\/11\/herbst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huxlipux.de\/blog\/"},{"@type":"ListItem","position":2,"name":"F\u00fcr Oma und Opa und Dich!"}]},{"@type":"WebSite","@id":"https:\/\/huxlipux.de\/blog\/#website","url":"https:\/\/huxlipux.de\/blog\/","name":"Huxlipux.de","description":"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huxlipux.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f","name":"Ursula B\u00f6hnke-Kuckhoff","sameAs":["http:\/\/www.huxlipux.de"],"url":"https:\/\/huxlipux.de\/blog\/author\/uweboe\/"}]}},"_links":{"self":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/1745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/comments?post=1745"}],"version-history":[{"count":16,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/1745\/revisions"}],"predecessor-version":[{"id":2406,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/1745\/revisions\/2406"}],"wp:attachment":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/media?parent=1745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/categories?post=1745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/tags?post=1745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}