{"id":15592,"date":"2013-12-28T12:30:01","date_gmt":"2013-12-28T11:30:01","guid":{"rendered":"http:\/\/huxlipux.de\/blog\/?p=15592"},"modified":"2013-12-28T22:11:15","modified_gmt":"2013-12-28T21:11:15","slug":"maennergespraechsrunde-und-danach","status":"publish","type":"post","link":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/","title":{"rendered":"M\u00e4nnergespr\u00e4chsrunde und danach"},"content":{"rendered":"<p style=\"text-align: center;\">Doktor Grauohr hatte die M\u00e4nner von Huxlipux wieder einmal zu einem gem\u00fctlichen Abend gerufen. Alle waren gern gekommen und erz\u00e4hlten von dem, was sie so zu tun haben. Der Weihnachtsmann rieb sich die F\u00fc\u00dfe, die ihm vom vielen Tanzen schon weh taten, und wollte sich verabschieden, um wieder ins Weihnachtsm\u00e4nnerland zur\u00fcck zu kehren. &#8222;Wie kommst du da hin?&#8220; fragte Hasenopa Karl.\u00a0&#8220; Ich rufe beim Flugplatz an, damit ein Flugzeug kommt. Sicherlich sind auch schon andere Weihnachtsm\u00e4nner zur\u00fcck. Vielleicht treffe ich sie auf dem Flugplatz. Aber zum Flugplatz muss ich hin laufen. Ist ja kein Schnee da.&#8220;<a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-M\u00e4nnergespr\u00e4che.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-15593\" alt=\"28.12. M\u00e4nnergespr\u00e4che\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-M\u00e4nnergespr\u00e4che.jpg\" width=\"410\" height=\"398\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-M\u00e4nnergespr\u00e4che.jpg 854w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-M\u00e4nnergespr\u00e4che-300x290.jpg 300w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/a> &#8222;Mann, Bopsi,&#8220; rief der Doktor, &#8222;Du schl\u00e4fst ja schon halb.&#8220; &#8220; Ich bin so m\u00fcde vom Aufpassen auf Kullatrulla, meinen kleinen Z\u00f6gling. &#8220; &#8222;Ja, ja, ich wei\u00df Bescheid,&#8220; f\u00fcgte das Waldm\u00e4nnlein zu.&#8220; Meine Kleine braucht auch meine strenge Aufsicht, damit sie nicht immer zu einem anderen rennt. &#8220; Aufmerksam h\u00f6rte Doktor Grauohr zu. Er dachte an das kleine Eselbaby und wie es wohl mit ihm sein w\u00fcrde.<\/p>\n<p style=\"text-align: center;\">Dann aber winkten sie alle dem Weihnachtsmann hinterher. Tsch\u00fc\u00df &#8220; rief der noch mal. &#8222;Wir Weihnachtsm\u00e4nner werden lauter Konfetti zu Weihnachten auf Huxlipux werfen lassen. Schnee k\u00f6nnen wir Euch leider nicht machen. Gr\u00fc\u00dft Eure Frauen und die Kinder, ich habe sie extra nicht in unsere Runde eingeladen, weil ich nicht m\u00f6chte, dass sie mir traurig nachschauen&#8220;<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Tsch\u00fc\u00df-W.mann_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-15594\" alt=\"28.12. Tsch\u00fc\u00df W.mann\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Tsch\u00fc\u00df-W.mann_.jpg\" width=\"437\" height=\"332\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Tsch\u00fc\u00df-W.mann_.jpg 1263w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Tsch\u00fc\u00df-W.mann_-300x228.jpg 300w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Tsch\u00fc\u00df-W.mann_-1024x778.jpg 1024w\" sizes=\"auto, (max-width: 437px) 100vw, 437px\" \/><\/a>Alle winkten dem Weihnachtsmann hinterher. Das Waldm\u00e4nnchen Hans aber wurde ganz rappelig. Es verabschiedete sich vom Doktor.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-15595\" alt=\"28.12. Klar, wenn du heim musst...\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg\" width=\"286\" height=\"325\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg 795w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst...-264x300.jpg 264w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/><\/a>&#8222;Klar, dann geh nur,&#8220; sagte der. &#8222;Du l\u00e4ufst schneller als der Weihnachtsmann, kannst dann schon mal einen Tee aufbr\u00fchen, und wenn er an Deinem H\u00e4uschen vorbeikommt, freut er sich \u00fcber einen warmen Schluck.&#8220; Er versprach, dass Hasenoma auf das M\u00e4dchen aufpassen w\u00fcrde und er es Neujahr abholen k\u00f6nne. Dann seien alle Weihnachtsm\u00e4nner durch und die Kleine h\u00e4tte mit den anderen Kinder Silvester ihren Spa\u00df gehabt.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Was-denn-noch-ein-W.Mann_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-15596\" alt=\"28.12. Was denn noch ein W.Mann=\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Was-denn-noch-ein-W.Mann_.jpg\" width=\"352\" height=\"298\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Was-denn-noch-ein-W.Mann_.jpg 733w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Was-denn-noch-ein-W.Mann_-300x254.jpg 300w\" sizes=\"auto, (max-width: 352px) 100vw, 352px\" \/><\/a>Was denn, noch ein Weihnachtsmann, dachte der Professor, aber dann sah er die Schlenkerbeine.\u00a0&#8222;Kullatrulla&#8220; rief er &#8222;Du bist doch kein Weihnachtsmann. Was soll das? Jetzt holen wir mal Deinen Papa.&#8220;<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Prof.Das-Kulla.darfst-du-nicht-mehr.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-15597\" alt=\"28.12. Prof.Das Kulla.darfst du nicht mehr\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Prof.Das-Kulla.darfst-du-nicht-mehr.jpg\" width=\"335\" height=\"273\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Prof.Das-Kulla.darfst-du-nicht-mehr.jpg 930w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Prof.Das-Kulla.darfst-du-nicht-mehr-300x244.jpg 300w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/><\/a>&#8222;Lieber Bopsipapa!&#8220; Kullatrulla ist betr\u00fcbt, dass Papa nicht lustig guckt. &#8222;Den Mantel hat mir doch der kleine Teddy Maxl geschenkt. Er will nicht immer wie ein Weihnachtsmann herumlaufen. Hasenoma strickt ihm schon was Warmes und ich hab doch kein M\u00e4ntelchen. Nein, ich wollte keinen verkohlen. Darf ich ihn behalten?<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Papa-nimmt-Ku.in-den-Arm.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-15598\" alt=\"28.12. Papa nimmt Ku.in den Arm\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Papa-nimmt-Ku.in-den-Arm.jpg\" width=\"324\" height=\"556\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Papa-nimmt-Ku.in-den-Arm.jpg 540w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Papa-nimmt-Ku.in-den-Arm-174x300.jpg 174w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/a> &#8222;Klar, musst ja nicht immer die Kapuze hochmachen, hast doch ein warmes H\u00fctchen auf dem Kopf.&#8220; Ein guter Papi, unser Clown Bopsi, nicht wahr?<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">Doktor Grauohr hatte die M\u00e4nner von Huxlipux wieder einmal zu einem gem\u00fctlichen Abend gerufen. Alle waren gern gekommen und erz\u00e4hlten von dem, was sie so zu tun haben. Der Weihnachtsmann&hellip; <span class=\"more-link\">more<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-15592","post","type-post","status-publish","format-standard","hentry","category-hasenoma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e4nnergespr\u00e4chsrunde und danach - Huxlipux.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e4nnergespr\u00e4chsrunde und danach - Huxlipux.de\" \/>\n<meta property=\"og:description\" content=\"Doktor Grauohr hatte die M\u00e4nner von Huxlipux wieder einmal zu einem gem\u00fctlichen Abend gerufen. Alle waren gern gekommen und erz\u00e4hlten von dem, was sie so zu tun haben. Der Weihnachtsmann&hellip; more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/\" \/>\n<meta property=\"og:site_name\" content=\"Huxlipux.de\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-28T11:30:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-12-28T21:11:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg\" \/>\n<meta name=\"author\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/\"},\"author\":{\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"headline\":\"M\u00e4nnergespr\u00e4chsrunde und danach\",\"datePublished\":\"2013-12-28T11:30:01+00:00\",\"dateModified\":\"2013-12-28T21:11:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/\"},\"wordCount\":437,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg\",\"articleSection\":[\"Hasenoma und ihre Freunde\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/\",\"url\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/\",\"name\":\"M\u00e4nnergespr\u00e4chsrunde und danach - Huxlipux.de\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg\",\"datePublished\":\"2013-12-28T11:30:01+00:00\",\"dateModified\":\"2013-12-28T21:11:15+00:00\",\"author\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"breadcrumb\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#primaryimage\",\"url\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg\",\"contentUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/huxlipux.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e4nnergespr\u00e4chsrunde und danach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\",\"url\":\"https:\/\/huxlipux.de\/blog\/\",\"name\":\"Huxlipux.de\",\"description\":\"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/huxlipux.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\",\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"sameAs\":[\"http:\/\/www.huxlipux.de\"],\"url\":\"https:\/\/huxlipux.de\/blog\/author\/uweboe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e4nnergespr\u00e4chsrunde und danach - Huxlipux.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/","og_locale":"de_DE","og_type":"article","og_title":"M\u00e4nnergespr\u00e4chsrunde und danach - Huxlipux.de","og_description":"Doktor Grauohr hatte die M\u00e4nner von Huxlipux wieder einmal zu einem gem\u00fctlichen Abend gerufen. Alle waren gern gekommen und erz\u00e4hlten von dem, was sie so zu tun haben. Der Weihnachtsmann&hellip; more","og_url":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/","og_site_name":"Huxlipux.de","article_published_time":"2013-12-28T11:30:01+00:00","article_modified_time":"2013-12-28T21:11:15+00:00","og_image":[{"url":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg","type":"","width":"","height":""}],"author":"Ursula B\u00f6hnke-Kuckhoff","twitter_misc":{"Verfasst von":"Ursula B\u00f6hnke-Kuckhoff","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#article","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/"},"author":{"name":"Ursula B\u00f6hnke-Kuckhoff","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"headline":"M\u00e4nnergespr\u00e4chsrunde und danach","datePublished":"2013-12-28T11:30:01+00:00","dateModified":"2013-12-28T21:11:15+00:00","mainEntityOfPage":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/"},"wordCount":437,"commentCount":0,"image":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#primaryimage"},"thumbnailUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg","articleSection":["Hasenoma und ihre Freunde"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/","url":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/","name":"M\u00e4nnergespr\u00e4chsrunde und danach - Huxlipux.de","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#primaryimage"},"image":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#primaryimage"},"thumbnailUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg","datePublished":"2013-12-28T11:30:01+00:00","dateModified":"2013-12-28T21:11:15+00:00","author":{"@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"breadcrumb":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#primaryimage","url":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg","contentUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/12\/28.12.-Klar-wenn-du-heim-musst....jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/huxlipux.de\/blog\/2013\/12\/maennergespraechsrunde-und-danach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huxlipux.de\/blog\/"},{"@type":"ListItem","position":2,"name":"M\u00e4nnergespr\u00e4chsrunde und danach"}]},{"@type":"WebSite","@id":"https:\/\/huxlipux.de\/blog\/#website","url":"https:\/\/huxlipux.de\/blog\/","name":"Huxlipux.de","description":"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huxlipux.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f","name":"Ursula B\u00f6hnke-Kuckhoff","sameAs":["http:\/\/www.huxlipux.de"],"url":"https:\/\/huxlipux.de\/blog\/author\/uweboe\/"}]}},"_links":{"self":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/15592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/comments?post=15592"}],"version-history":[{"count":3,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/15592\/revisions"}],"predecessor-version":[{"id":15622,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/15592\/revisions\/15622"}],"wp:attachment":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/media?parent=15592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/categories?post=15592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/tags?post=15592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}