{"id":14516,"date":"2013-11-12T15:12:08","date_gmt":"2013-11-12T14:12:08","guid":{"rendered":"http:\/\/huxlipux.de\/blog\/?p=14516"},"modified":"2013-11-13T00:31:54","modified_gmt":"2013-11-12T23:31:54","slug":"viel-zu-gucken","status":"publish","type":"post","link":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/","title":{"rendered":"Viel zu gucken?"},"content":{"rendered":"<p>Heute nochmal zusammengefasst in der Kindergalerie :<br \/>\nUnsere erste Klasse!<a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl..jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-14448\" alt=\"Sonnefehlt nicht mehr wir lernen in der Sonnenkl.\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl.-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p>Vielleicht d\u00fcrft Ihr Euch diesen Beitrag ausdrucken? Die Bildchen<br \/>\nausschneiden? Es f\u00e4llt Euch gewiss etwas dazu ein.<\/p>\n<h2><span style=\"color: #ff0000;\">*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*<\/span><\/h2>\n<p>Schreibt uns doch mal, ob Ihr es gut findet, wenn ab und zu, manchmal jeden Tag etwas Neues dazu kommt.<\/p>\n<p>\u00dcbrigens Hasenoma hat ein sehr sch\u00f6nes Buch gelesen <a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Das-H\u00e4uschen-Irgendwo.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14518\" alt=\"Das H\u00e4uschen Irgendwo\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Das-H\u00e4uschen-Irgendwo.gif\" width=\"1\" height=\"1\" \/><\/a><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Das-H\u00e4uschen-Irgendwo-von-Sabine-Maria-Sch\u00f6neich.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-14519\" alt=\"Das H\u00e4uschen Irgendwo von Sabine Maria Sch\u00f6neich\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Das-H\u00e4uschen-Irgendwo-von-Sabine-Maria-Sch\u00f6neich-150x150.jpg\" width=\"150\" height=\"150\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Das-H\u00e4uschen-Irgendwo-von-Sabine-Maria-Sch\u00f6neich-150x150.jpg 150w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Das-H\u00e4uschen-Irgendwo-von-Sabine-Maria-Sch\u00f6neich.jpg 160w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><br \/>\n\u00fcber zwei Katzen, 5 Schnecken, ein Eichh\u00f6rnchen,<br \/>\neine Spinne und eine Fledermaus. Das k\u00f6nnt Ihr<br \/>\nEuch zu Weihnachten schenken lassen: Das H\u00e4uschen Irgendwo von Sabine Maria Sch\u00f6neich<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">Heute nochmal zusammengefasst in der Kindergalerie : Unsere erste Klasse! Vielleicht d\u00fcrft Ihr Euch diesen Beitrag ausdrucken? Die Bildchen ausschneiden? Es f\u00e4llt Euch gewiss etwas dazu ein. *\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0* Schreibt uns&hellip; <span class=\"more-link\">more<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-14516","post","type-post","status-publish","format-standard","hentry","category-neues-aus-huxlipux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viel zu gucken? - Huxlipux.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viel zu gucken? - Huxlipux.de\" \/>\n<meta property=\"og:description\" content=\"Heute nochmal zusammengefasst in der Kindergalerie : Unsere erste Klasse! Vielleicht d\u00fcrft Ihr Euch diesen Beitrag ausdrucken? Die Bildchen ausschneiden? Es f\u00e4llt Euch gewiss etwas dazu ein. *\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0* Schreibt uns&hellip; more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/\" \/>\n<meta property=\"og:site_name\" content=\"Huxlipux.de\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-12T14:12:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-11-12T23:31:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl..jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1009\" \/>\n\t<meta property=\"og:image:height\" content=\"766\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/\"},\"author\":{\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"headline\":\"Viel zu gucken?\",\"datePublished\":\"2013-11-12T14:12:08+00:00\",\"dateModified\":\"2013-11-12T23:31:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/\"},\"wordCount\":90,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl.-150x150.jpg\",\"articleSection\":[\"Dinge des Tages\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/\",\"url\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/\",\"name\":\"Viel zu gucken? - Huxlipux.de\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl.-150x150.jpg\",\"datePublished\":\"2013-11-12T14:12:08+00:00\",\"dateModified\":\"2013-11-12T23:31:54+00:00\",\"author\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"breadcrumb\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#primaryimage\",\"url\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl.-150x150.jpg\",\"contentUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl.-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/huxlipux.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Viel zu gucken?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\",\"url\":\"https:\/\/huxlipux.de\/blog\/\",\"name\":\"Huxlipux.de\",\"description\":\"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/huxlipux.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\",\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"sameAs\":[\"http:\/\/www.huxlipux.de\"],\"url\":\"https:\/\/huxlipux.de\/blog\/author\/uweboe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viel zu gucken? - Huxlipux.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/","og_locale":"de_DE","og_type":"article","og_title":"Viel zu gucken? - Huxlipux.de","og_description":"Heute nochmal zusammengefasst in der Kindergalerie : Unsere erste Klasse! Vielleicht d\u00fcrft Ihr Euch diesen Beitrag ausdrucken? Die Bildchen ausschneiden? Es f\u00e4llt Euch gewiss etwas dazu ein. *\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0*\u00b0* Schreibt uns&hellip; more","og_url":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/","og_site_name":"Huxlipux.de","article_published_time":"2013-11-12T14:12:08+00:00","article_modified_time":"2013-11-12T23:31:54+00:00","og_image":[{"width":1009,"height":766,"url":"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl..jpg","type":"image\/jpeg"}],"author":"Ursula B\u00f6hnke-Kuckhoff","twitter_misc":{"Verfasst von":"Ursula B\u00f6hnke-Kuckhoff"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#article","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/"},"author":{"name":"Ursula B\u00f6hnke-Kuckhoff","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"headline":"Viel zu gucken?","datePublished":"2013-11-12T14:12:08+00:00","dateModified":"2013-11-12T23:31:54+00:00","mainEntityOfPage":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/"},"wordCount":90,"commentCount":0,"image":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#primaryimage"},"thumbnailUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl.-150x150.jpg","articleSection":["Dinge des Tages"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/","url":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/","name":"Viel zu gucken? - Huxlipux.de","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#primaryimage"},"image":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#primaryimage"},"thumbnailUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl.-150x150.jpg","datePublished":"2013-11-12T14:12:08+00:00","dateModified":"2013-11-12T23:31:54+00:00","author":{"@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"breadcrumb":{"@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#primaryimage","url":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl.-150x150.jpg","contentUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2013\/11\/Sonnefehlt-nicht-mehr-wir-lernen-in-der-Sonnenkl.-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/huxlipux.de\/blog\/2013\/11\/viel-zu-gucken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huxlipux.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Viel zu gucken?"}]},{"@type":"WebSite","@id":"https:\/\/huxlipux.de\/blog\/#website","url":"https:\/\/huxlipux.de\/blog\/","name":"Huxlipux.de","description":"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huxlipux.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f","name":"Ursula B\u00f6hnke-Kuckhoff","sameAs":["http:\/\/www.huxlipux.de"],"url":"https:\/\/huxlipux.de\/blog\/author\/uweboe\/"}]}},"_links":{"self":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/14516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/comments?post=14516"}],"version-history":[{"count":4,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/14516\/revisions"}],"predecessor-version":[{"id":14533,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/14516\/revisions\/14533"}],"wp:attachment":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/media?parent=14516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/categories?post=14516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/tags?post=14516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}