{"id":1381,"date":"2011-10-01T06:52:19","date_gmt":"2011-10-01T04:52:19","guid":{"rendered":"http:\/\/huxlipux.de\/blog\/?p=1381"},"modified":"2011-10-20T14:58:50","modified_gmt":"2011-10-20T12:58:50","slug":"ein-untermieter-zieht-ein","status":"publish","type":"post","link":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/","title":{"rendered":"Ein Untermieter zieht ein"},"content":{"rendered":"<h4>Professor Schlamperbein<\/h4>\n<p>Eines Tages klopft es an die T\u00fcr. Hasenoma \u00f6ffnet. Ein kleiner Herr hockt hinter einem Globus und\u00a0 gr\u00fc\u00dft freundlich. Er stellt sich vor. \u201eProfessor Schlamp. Ich suche ein Zimmer.\u201c<a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1557\" title=\"IMG_2378\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg\" alt=\"\" width=\"195\" height=\"300\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg 195w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781.jpg 667w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/a><\/p>\n<p>Hasenoma bittet den Professor herein. Er schiebt seine Brille von der Nase hoch. \u201eich habe meine Schwierigkeiten mit ihr.\u201c Erkl\u00e4rt er und meint die Brille. \u201eSie ist erst neu. Ja, ich suche einen ruhigen Raum, in dem ich arbeiten kann. Mein Forschungsauftrag befasst sich mit Autos.\u00a0 Und wenn es sein kann, w\u00fcrde ich auch gern bei ihnen mitessen.\u201c Oma denkt an ihre muntere Schar. \u201eOb meine Mitbewohner immer ruhig sind, das kann ich nicht versprechen. Aber wie w\u00e4re es mit einer Probewoche?\u201c Ja, gut. Der kleine Professor, der wirklich ziemlich winzig ist, kann einziehen.<\/p>\n<p>Als er zum ersten Mal am Mittagstisch erscheint sind alle sehr gespannt auf ihn. Er erz\u00e4hlt:<br \/>\n\u201eIch muss ein Auto erfinden, das bei einem Stau auf der Autobahn fliegen kann und ganz leise ist, damit die Leute nicht gest\u00f6rt werden, wenn es ihr Haus \u00fcberfliegt und es soll auf allen Erdteilen verkehren.\u201c Alle sind begeistert. \u201eKann man ihnen dabei helfen?\u201c Fragt Bopsi, der Clown. Der Professor nickt. \u201eJa gern. Ich habe n\u00e4mlich noch nicht die richtige Idee. Ihr k\u00f6nnt alle Vorschl\u00e4ge machen, wie ihr euch so ein Auto vorstellt. Am besten w\u00e4re, es k\u00f6nnte ohne Benzin fliegen.\u201c \u201eVielleicht mit Himbeerwasser?\u201c Hasenoma \u00fcberlegt. \u201eNa ja\u201c. Der L\u00f6we Gutlieb findet Himbeerwasser geht nicht.\u00a0 Aber auch er denkt eifrig nach. Das kleine Entchen schnattert freudig\u00a0 \u201eJa, ja, ja, ja!\u201c Der Professor gibt ihm gleich Papier und Stifte. Er mag das Entchen sofort, weil es so klein \u00a0oder so gro\u00df ist wie er.<\/p>\n<p>\u201eIch kann am besten denken, wenn ich mir die Ohren mit meinen F\u00fc\u00dfen zuhalte. So.\u201c Er setzt sich auf den Tisch, damit es alle gut sehen k\u00f6nnen. Die anderen probieren das sofort nach zu machen, aber keinem gelingt das Kunstst\u00fcck. Solche bewegliche Beine hat nur der kleine Professor. Giraffe Susi verh\u00e4kelt sich fast die Beine. Das Entchen meint aufgeregt, vielleicht w\u00fcsste es ja, wie man fliegen k\u00f6nne. Es versucht, ein St\u00fcckchen zu schweben. Doch torkelt es noch und muss erst kr\u00e4ftiger werden, um wie die gro\u00dfen Enten am See,\u00a0 fliegen zu k\u00f6nnen.<\/p>\n<p>Das Telefon l\u00e4utet. Der Professor h\u00e4lt einen seiner F\u00fc\u00dfe ans Ohr. Er denkt,\u00a0 er w\u00e4re das Telefon. Aber da er nichts h\u00f6rt, legt er verlegen den Fu\u00df wieder ab. Die anderen lachen.<\/p>\n<h3>Das ist aber auch zu komisch. Professor Schlamperbein nennt ihn Bopsi. Ach und der findet das sogar besser, als Schlamp zu hei\u00dfen. Seine Studenten kichern n\u00e4mlich hinter ihm und meinen, er w\u00e4re ein wenig schlampig oder auch vergesslich und h\u00e4tte den richtigen Namen. Aber das ist hier nun vorbei, was den kleinen Professor richtig strahlen l\u00e4sst. Nur wenn der Brieftr\u00e4ger ein P\u00e4ckchen bringen wird f\u00fcr Herrn Professor Schlamp, k\u00f6nnte er seinen alten Namen wieder h\u00f6ren. Und hier ein paar Fotos, damit ihr etwas \u00fcber das Leben in der Huxlipux-Wohngemeinschaft mit dem winzigen Untermieter erfahrt.<\/h3>\n<p>Unbequem an der Sch\u00fcssel h\u00e4ngend\u00a0 zu essen.<\/p>\n<p>Schnell ist ein Bett aus Pappe gezaubert.<\/p>\n<p>Flux hat eine gute Idee. &#8222;Bitte auf dem Eierbecher Platz nehmen!&#8220;<\/p>\n<p>Gleich kann der kleine Professor besser mit allen essen.<\/p>\n<p>Das kleine St\u00fchlchen ist wohl aus einer alten Puppenstube?<\/p>\n<p>Omas alte angebrochene Brille w\u00e4re nichts f\u00fcr den kleinen Professor.<\/p>\n<p><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP36021.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1561\" title=\"IMGP3602\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP36021-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP36021-300x201.jpg 300w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP36021.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3636.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1564\" title=\"IMGP3636\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3636-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3636-300x201.jpg 300w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3636.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP36401.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1565\" title=\"IMGP3640\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP36401-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP36401-300x201.jpg 300w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP36401.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3643.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1566\" title=\"IMGP3643\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3643-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3643-300x201.jpg 300w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3643.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3646.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-1567\" title=\"IMGP3646\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3646-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3646-300x201.jpg 300w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3646.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3614.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1568\" title=\"IMGP3614\" src=\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3614-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3614-300x201.jpg 300w, https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMGP3614.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">Professor Schlamperbein Eines Tages klopft es an die T\u00fcr. Hasenoma \u00f6ffnet. Ein kleiner Herr hockt hinter einem Globus und\u00a0 gr\u00fc\u00dft freundlich. Er stellt sich vor. \u201eProfessor Schlamp. Ich suche ein&hellip; <span class=\"more-link\">more<\/span><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1381","post","type-post","status-publish","format-standard","hentry","category-hasenoma"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Untermieter zieht ein - Huxlipux.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Untermieter zieht ein - Huxlipux.de\" \/>\n<meta property=\"og:description\" content=\"Professor Schlamperbein Eines Tages klopft es an die T\u00fcr. Hasenoma \u00f6ffnet. Ein kleiner Herr hockt hinter einem Globus und\u00a0 gr\u00fc\u00dft freundlich. Er stellt sich vor. \u201eProfessor Schlamp. Ich suche ein&hellip; more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/\" \/>\n<meta property=\"og:site_name\" content=\"Huxlipux.de\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-01T04:52:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-10-20T12:58:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"667\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ursula B\u00f6hnke-Kuckhoff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/\"},\"author\":{\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"headline\":\"Ein Untermieter zieht ein\",\"datePublished\":\"2011-10-01T04:52:19+00:00\",\"dateModified\":\"2011-10-20T12:58:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/\"},\"wordCount\":592,\"commentCount\":2,\"image\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg\",\"articleSection\":[\"Hasenoma und ihre Freunde\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/\",\"url\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/\",\"name\":\"Ein Untermieter zieht ein - Huxlipux.de\",\"isPartOf\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg\",\"datePublished\":\"2011-10-01T04:52:19+00:00\",\"dateModified\":\"2011-10-20T12:58:50+00:00\",\"author\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\"},\"breadcrumb\":{\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#primaryimage\",\"url\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg\",\"contentUrl\":\"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/huxlipux.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Untermieter zieht ein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#website\",\"url\":\"https:\/\/huxlipux.de\/blog\/\",\"name\":\"Huxlipux.de\",\"description\":\"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/huxlipux.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f\",\"name\":\"Ursula B\u00f6hnke-Kuckhoff\",\"sameAs\":[\"http:\/\/www.huxlipux.de\"],\"url\":\"https:\/\/huxlipux.de\/blog\/author\/uweboe\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Untermieter zieht ein - Huxlipux.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/","og_locale":"de_DE","og_type":"article","og_title":"Ein Untermieter zieht ein - Huxlipux.de","og_description":"Professor Schlamperbein Eines Tages klopft es an die T\u00fcr. Hasenoma \u00f6ffnet. Ein kleiner Herr hockt hinter einem Globus und\u00a0 gr\u00fc\u00dft freundlich. Er stellt sich vor. \u201eProfessor Schlamp. Ich suche ein&hellip; more","og_url":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/","og_site_name":"Huxlipux.de","article_published_time":"2011-10-01T04:52:19+00:00","article_modified_time":"2011-10-20T12:58:50+00:00","og_image":[{"width":667,"height":1024,"url":"https:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781.jpg","type":"image\/jpeg"}],"author":"Ursula B\u00f6hnke-Kuckhoff","twitter_misc":{"Verfasst von":"Ursula B\u00f6hnke-Kuckhoff","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#article","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/"},"author":{"name":"Ursula B\u00f6hnke-Kuckhoff","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"headline":"Ein Untermieter zieht ein","datePublished":"2011-10-01T04:52:19+00:00","dateModified":"2011-10-20T12:58:50+00:00","mainEntityOfPage":{"@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/"},"wordCount":592,"commentCount":2,"image":{"@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#primaryimage"},"thumbnailUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg","articleSection":["Hasenoma und ihre Freunde"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/","url":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/","name":"Ein Untermieter zieht ein - Huxlipux.de","isPartOf":{"@id":"https:\/\/huxlipux.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#primaryimage"},"image":{"@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#primaryimage"},"thumbnailUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg","datePublished":"2011-10-01T04:52:19+00:00","dateModified":"2011-10-20T12:58:50+00:00","author":{"@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f"},"breadcrumb":{"@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#primaryimage","url":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg","contentUrl":"http:\/\/huxlipux.de\/blog\/wp-content\/uploads\/2011\/10\/IMG_23781-195x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/huxlipux.de\/blog\/2011\/10\/ein-untermieter-zieht-ein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/huxlipux.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Ein Untermieter zieht ein"}]},{"@type":"WebSite","@id":"https:\/\/huxlipux.de\/blog\/#website","url":"https:\/\/huxlipux.de\/blog\/","name":"Huxlipux.de","description":"Kinder-Geschichten Blog f\u00fcr Kinder von 3 bis 99","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huxlipux.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/huxlipux.de\/blog\/#\/schema\/person\/f2a857fac0c9223e32b50adc8a05fa1f","name":"Ursula B\u00f6hnke-Kuckhoff","sameAs":["http:\/\/www.huxlipux.de"],"url":"https:\/\/huxlipux.de\/blog\/author\/uweboe\/"}]}},"_links":{"self":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/comments?post=1381"}],"version-history":[{"count":17,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/1381\/revisions"}],"predecessor-version":[{"id":1477,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/posts\/1381\/revisions\/1477"}],"wp:attachment":[{"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/media?parent=1381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/categories?post=1381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/huxlipux.de\/blog\/wp-json\/wp\/v2\/tags?post=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}